
{"id":4878,"date":"2010-05-13T00:00:00","date_gmt":"2010-05-12T22:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/collegio\/convenzione-con-bps-e-logos-finanziariaper-finanziamenti-a-pensionati-e-pensionandi-con-cessione-del-quinto-della-pensione\/"},"modified":"2010-05-13T00:00:00","modified_gmt":"2010-05-12T22:00:00","slug":"convenzione-con-bps-e-logos-finanziariaper-finanziamenti-a-pensionati-e-pensionandi-con-cessione-del-quinto-della-pensione","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/collegio\/convenzione-con-bps-e-logos-finanziariaper-finanziamenti-a-pensionati-e-pensionandi-con-cessione-del-quinto-della-pensione\/","title":{"rendered":"Convenzione con BPS e Logos Finanziaria&nbsp;per finanziamenti a pensionati e pensionandi con cessione del quinto della pensione."},"content":{"rendered":"<p><a target='_blank' href='http:\/\/www.geometrire.it\/cms_rc\/allegati\/1550__2308_Finanziamento_a_pensionati_e_pensionandi.pdf'>Circolare CIPAG Prot 44 del 12_05_2010<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Circolare CIPAG Prot 44 del 12_05_2010<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4878"}],"collection":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/comments?post=4878"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4878\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/media?parent=4878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/categories?post=4878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/tags?post=4878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}