
{"id":4838,"date":"2010-07-15T00:00:00","date_gmt":"2010-07-14T22:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/collegio\/commissione-n-10-verbale-n-32010-del-09072010\/"},"modified":"2010-07-15T00:00:00","modified_gmt":"2010-07-14T22:00:00","slug":"commissione-n-10-verbale-n-32010-del-09072010","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/collegio\/commissione-n-10-verbale-n-32010-del-09072010\/","title":{"rendered":"Commissione n.&nbsp;10 &#8211; Verbale n.&nbsp;3\/2010 del 09\/07\/2010"},"content":{"rendered":"<p><a target='_blank' href='http:\/\/www.geometrire.it\/cms_rc\/allegati\/1593__0050_VERBALE_3_COMMISSIONE_10_DEL_09_07_2010.pdf'>Commissione n. 10 &#8211; Verbale n. 3\/2010 del 09\/07\/2010 <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Commissione n. 10 &#8211; Verbale n. 3\/2010 del 09\/07\/2010<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4838"}],"collection":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/comments?post=4838"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4838\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/media?parent=4838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/categories?post=4838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/tags?post=4838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}