
{"id":4789,"date":"2010-09-30T00:00:00","date_gmt":"2010-09-29T22:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/collegio\/regione-emilia-romagna-dgr-13622010-recante-modifica-degli-allegati-di-cui-alla-parte-seconda-della-dal-15608\/"},"modified":"2010-09-30T00:00:00","modified_gmt":"2010-09-29T22:00:00","slug":"regione-emilia-romagna-dgr-13622010-recante-modifica-degli-allegati-di-cui-alla-parte-seconda-della-dal-15608","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/collegio\/regione-emilia-romagna-dgr-13622010-recante-modifica-degli-allegati-di-cui-alla-parte-seconda-della-dal-15608\/","title":{"rendered":"Regione Emilia-Romagna: DGR 1362\/2010 recante &quot;Modifica degli Allegati di cui alla parte seconda della DAL 156\/08&quot;"},"content":{"rendered":"<p>EMILIA-ROMAGNA: CAMBIA LA DISCIPLINA REGIONALE RELATIVA AL RENDIMENTO ENERGETICO DEGLI EDIFICI E ALLE PROCEDURE DI CERTIFICAZIONE ENERGETICA Pubblicata oggi sul Bollettino Ufficiale della regione Emilia Romagna la Delibera n. 1362, recante &ldquo;Modifica degli Allegati di cui alla parte seconda della DAL 156\/08&rdquo; sugli &nbsp;indirizzi regionali in merito ai requisiti di rendimento energetico e sulle procedure di certificazione energetica degli edifici. A partire da oggi dovranno essere applicate le nuove disposizioni in materia di requisiti minimi di prestazione energetica e&nbsp;di certificazione energetica degli edifici, queste le principali modifiche sono le seguenti: &nbsp;REQUISITI MINIMI DI PRESTAZIONE ENERGETICA:&nbsp; La verifica del rendimento medio stagionale degli impianti di climatizzazione non &egrave; pi&ugrave; richiesta nel caso di interventi edilizi di cui al punto 3.1 lett. a) della DAL 156\/08 (ovvero edifici di nuova costruzione; demolizione totale e ricostruzione degli edifici esistenti; ristrutturazione integrale di edifici esistenti di superficie utile superiore a 1000 m2; ampliamento edifici con volume superiore al 20% di quello dell&rsquo;edificio esistente).&nbsp;La verifica del rendimento medio stagionale &egrave; ancora richiesta negli altri casi, ovvero per: &nbsp;nuova installazione o ristrutturazione di impianti termici in edifici esistenti &nbsp;sostituzione di generatori di calore &nbsp;Per gli interventi edilizi di cui al punto 3.1 lett. c) della DAL 156\/08, viene introdotta la possibilit&agrave; di effettuare la verifica dell&rsquo;indice di prestazione energetica (come nel caso di nuovi edifici), in alternativa alla verifica delle trasmittanze termiche delle chiusure&nbsp;Obbligo di rispettare, negli interventi edilizi di cui al punto 3.1 lett. a) della DAL 156\/08, livelli minimi di prestazione energetica per il raffrescamento estivo (Epe,invol) in termini di fabbisogno di energia termica dell&rsquo;edificio &nbsp;Livelli di prestazione energetica pi&ugrave; severi (del 10%) per gli edifici pubblici (ad uso pubblico o di propriet&agrave; pubblica) &nbsp;Possibilit&agrave; di derogare all&rsquo;obbligo di installazione di impianti centralizzati, in presenza di specifica relazione sottoscritta da un tecnico abilitato che attesti il conseguimento di un analogo o migliore rendimento energetico dell&rsquo;edificio mediante l&rsquo;utilizzo di una diversa tipologia d&rsquo;impianto &nbsp;Nuova definizione di energia da fonti rinnovabili (da direttiva 28\/2009\/CE, con conseguente&nbsp; possibilit&agrave; di valorizzare il contributo delle pompe di calore) e aggiornamento dei requisiti in materia di obbligo di installazione di impianti di produzione di energia da FER &nbsp;Per gli impianti alimentati a biomasse (pellets, cippato, etc.), introduzione di requisiti minimi di efficienza del generatore e obbligo di verifica dei valori di trasmittanza dell&rsquo;involucro edilizio &nbsp;Quando siano obbligatorie le verifiche necessarie a garantire il contenimento dei consumi energetici in regime estivo, viene introdotta la possibilit&agrave; di fare riferimento alla trasmittanza termica periodica dell&rsquo;involucro edilizio, in alternativa alla massa superficiale &nbsp;&nbsp;PROCEDURE DI CERTIFICAZIONE ENERGETICA: &nbsp;Specificazione dei casi in cui la certificazione energetica dell&rsquo;immobile non &egrave; obbligatoria, con riferimento sia alle tipologie edilizie dell&rsquo;immobile stesso, sia alle casistiche di cessione a titolo oneroso&nbsp;Introduzione di una specifica classificazione dell&rsquo;immobile in relazione al fabbisogno di energia termica per la climatizzazione estiva&nbsp;Introduzione di una nuova forma grafica di rappresentazione della prestazione termica (il cosiddetto &ldquo;cruscotto&rdquo;) in aggiunta alla classe energetica&nbsp;Specificazione delle modalit&agrave; di certificazione delle singole unit&agrave; immobiliari&nbsp;Puntuale definizione delle modalit&agrave; di svolgimento della procedura di certificazione energetica, con l&rsquo;obbligo &ndash; nel caso delle nuove costruzioni &ndash; di nomina del certificatore prima dell&rsquo;inizio lavori, e dell&rsquo;esecuzione di verifiche e controlli in corso d&rsquo;opera&nbsp;Obbligo di apposizione della &ldquo;targa energetica&rdquo; per gli edifici di nuova costruzione (il modello di &ldquo;targa energetica&rdquo; verr&agrave; definito con apposito atto, in via di predisposizione)&nbsp;La procedura di autodichiarazione da parte del proprietario, prevista al punto 9 delle linee-guida nazionali, NON viene introdotta nella norma regionale&nbsp;<\/p>\n<p><a target='_blank' href='http:\/\/www.geometrire.it\/cms_rc\/allegati\/1646__2109_DGR_ER_20_09_2010_1362_cert_energetica.pdf'>DGR ER 20 09 2010 pubblicato 30\/09\/2010<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EMILIA-ROMAGNA: CAMBIA LA DISCIPLINA REGIONALE RELATIVA AL RENDIMENTO ENERGETICO DEGLI EDIFICI E ALLE PROCEDURE DI CERTIFICAZIONE ENERGETICA Pubblicata oggi sul Bollettino Ufficiale della regione Emilia Romagna la Delibera n. 1362, recante &ldquo;Modifica degli Allegati di cui alla parte seconda della DAL 156\/08&rdquo; sugli &nbsp;indirizzi regionali in merito ai requisiti di rendimento energetico e sulle procedure di certificazione energetica degli edifici. A partire da oggi dovranno essere applicate le nuove disposizioni in materia di requisiti minimi di prestazione energetica e&nbsp;di certificazione energetica degli edifici, queste le principali modifiche sono le seguenti: &nbsp;REQUISITI MINIMI DI PRESTAZIONE ENERGETICA:&nbsp; La verifica del rendimento medio&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4789"}],"collection":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/comments?post=4789"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4789\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/media?parent=4789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/categories?post=4789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/tags?post=4789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}