
{"id":4693,"date":"2011-02-18T00:00:00","date_gmt":"2011-02-17T23:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/collegio\/cassa-italiana-geometri-comunicazione-recupero-password\/"},"modified":"2011-02-18T00:00:00","modified_gmt":"2011-02-17T23:00:00","slug":"cassa-italiana-geometri-comunicazione-recupero-password","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/collegio\/cassa-italiana-geometri-comunicazione-recupero-password\/","title":{"rendered":"Cassa Italiana Geometri &#8211; comunicazione recupero password"},"content":{"rendered":"<p>Informiamo, che dal 16 febbraio&nbsp;2011 &egrave; stato attivato il servizio on-line per il recupero della password sul portale della CIPAG <a href=\"http:\/\/www.cassageometri.it\/\">www.cassageometri.it<\/a> .Tutti gli iscritti potranno d&acute;ora in poi richiedere la password rapidamente, nel caso l&acute;avessero smarrita o non la ricordassero, semplicemente cliccando sul link &lsquo;Recupera Password&acute;, posizionato sotto la sezione di accesso all&acute;area riservata. Una volta entrati nell&acute;area di recupero della password sar&agrave; sufficiente inserire il numero di matricola e l&acute;indirizzo di posta elettronica certificata (P.E.C.) presente nella propria anagrafica. Una volta effettuato questo veloce passaggio la password verr&agrave; immediatamente inviata all&acute;indirizzo P.E.C.; in caso non si disponesse di una casella P.E.C. si pu&ograve; richiedere la password contattando il Numero Verde 800 65 58 73 e comunicando all&acute;operatore il proprio numero di matricola ed il proprio codice fiscale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informiamo, che dal 16 febbraio&nbsp;2011 &egrave; stato attivato il servizio on-line per il recupero della password sul portale della CIPAG www.cassageometri.it .Tutti gli iscritti potranno d&acute;ora in poi richiedere la password rapidamente, nel caso l&acute;avessero smarrita o non la ricordassero, semplicemente cliccando sul link &lsquo;Recupera Password&acute;, posizionato sotto la sezione di accesso all&acute;area riservata. Una volta entrati nell&acute;area di recupero della password sar&agrave; sufficiente inserire il numero di matricola e l&acute;indirizzo di posta elettronica certificata (P.E.C.) presente nella propria anagrafica. Una volta effettuato questo veloce passaggio la password verr&agrave; immediatamente inviata all&acute;indirizzo P.E.C.; in caso non si disponesse di una&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4693"}],"collection":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/comments?post=4693"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4693\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/media?parent=4693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/categories?post=4693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/tags?post=4693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}