
{"id":4335,"date":"2013-11-08T00:00:00","date_gmt":"2013-11-07T23:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/collegio\/cassa-geometri-indagine-iscritti-comunit-europea-comunicazione-del-presidente\/"},"modified":"2013-11-08T00:00:00","modified_gmt":"2013-11-07T23:00:00","slug":"cassa-geometri-indagine-iscritti-comunit-europea-comunicazione-del-presidente","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/collegio\/cassa-geometri-indagine-iscritti-comunit-europea-comunicazione-del-presidente\/","title":{"rendered":"Cassa Geometri &#8211; indagine iscritti Comunit&agrave; Europea &#8211; comunicazione del Presidente"},"content":{"rendered":"<p>Si pubblica e-mail del 04\/11\/2013&nbsp;&#8212;&nbsp;Caro Presidente,ho il piacere di informarTi che la CIPAG, insieme all&rsquo;Adepp, nell&rsquo;ambito del Piano di Azione Imprenditorialit&agrave; 2020 e del Tavolo di lavoro sulle Libere Professioni avviato dalla Commissione Europea,&nbsp; sta realizzando un&rsquo;indagine per la valutazione dei bisogni specifici della nostra Categoria.A questo fine abbiamo inviato una comunicazione a tutti i nostri iscritti chiedendo il loro strategico contributo con le risposte ad un questionario predisposto sulla base delle indicazioni della stessa Comunit&agrave; Europea.Attraverso le risposte fornite vogliamo rilevare&nbsp; le esigenze dei geometri in relazione a tematiche come la semplificazione, l`internazionalizzazione, l`accesso al credito ed il welfare.I risultati che otterremo ci daranno l&rsquo;opportunit&agrave; di incidere in modo mirato sulla programmazione comunitaria per i prossimi interventi e misure a sostegno della libera professione.Proprio per questo sar&agrave; importante avere un ampio riscontro nelle risposte ai questionari e proprio per questo chiediamo la Tua collaborazione nel promuovere il coinvolgimento degli iscritti al Tuo Collegio.&nbsp; Il questionario che abbiamo inviato andr&agrave; compilato entro il 10 novembre 2013. &nbsp;Nel ringraziarTi per l&rsquo;attenzione e sperando nellaTua fattiva collaborazione,Ti saluto cordialmente&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; F.to &nbsp; &nbsp; Fausto AmadasiPresidente CIPAG &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si pubblica e-mail del 04\/11\/2013&nbsp;&#8212;&nbsp;Caro Presidente,ho il piacere di informarTi che la CIPAG, insieme all&rsquo;Adepp, nell&rsquo;ambito del Piano di Azione Imprenditorialit&agrave; 2020 e del Tavolo di lavoro sulle Libere Professioni avviato dalla Commissione Europea,&nbsp; sta realizzando un&rsquo;indagine per la valutazione dei bisogni specifici della nostra Categoria.A questo fine abbiamo inviato una comunicazione a tutti i nostri iscritti chiedendo il loro strategico contributo con le risposte ad un questionario predisposto sulla base delle indicazioni della stessa Comunit&agrave; Europea.Attraverso le risposte fornite vogliamo rilevare&nbsp; le esigenze dei geometri in relazione a tematiche come la semplificazione, l`internazionalizzazione, l`accesso al credito ed il welfare.I&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4335"}],"collection":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/comments?post=4335"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4335\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/media?parent=4335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/categories?post=4335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/tags?post=4335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}