
{"id":4333,"date":"2013-11-12T00:00:00","date_gmt":"2013-11-11T23:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/collegio\/avviso-importante-cassa-geometri-irregolarit-contributive-preavviso-cartella-esattoriale\/"},"modified":"2013-11-12T00:00:00","modified_gmt":"2013-11-11T23:00:00","slug":"avviso-importante-cassa-geometri-irregolarit-contributive-preavviso-cartella-esattoriale","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/collegio\/avviso-importante-cassa-geometri-irregolarit-contributive-preavviso-cartella-esattoriale\/","title":{"rendered":"AVVISO IMPORTANTE CASSA GEOMETRI &#8211; Irregolarit&agrave; contributive, preavviso cartella esattoriale"},"content":{"rendered":"<p>Di seguito si riporta la comunicazione ricevuta in data odierna dalla Direzione Generale della CIPAG&nbsp;di preavviso emissione cartella esattoriale per le irregolarit&agrave; contributive&nbsp;anni 2007 &#8211; 2011, sanabili sul Portale dei Pagamenti entro il 15\/11\/2013:Spettabile Collegio,&nbsp;si ricorda che nell`ambito delle verifiche periodicamente compiute sulle posizioni contributive degli iscritti, la Cipag ha effettuato il controllo sul quinquennio 2007-2011 allo scopo di evitare che la relativa contribuzione si prescriva, rendendo invalidi gli anni ai fini previdenziali.&nbsp;Delle singole posizioni irregolari sono stati informati, lo scorso mese di luglio, tutti gli interessati con dettagliate comunicazioni personalizzate (via pec o posta raccomandata) che li invitavano, nel contempo, a mettersi in regola tramite il Portale dei pagamenti, per evitare la notifica della cartella esattoriale gravata degli aggi esattoriali e della maggiorazione&nbsp; delle sanzioni.&nbsp;Tramite il versamento sul Portale dei pagamenti, come &egrave; noto, si usufruisce di condizioni agevolate; ad esempio sanzione per omesso versamento nella misura del 10% piuttosto che del&nbsp; 25%&nbsp; ed interessi nella misura del 2,5% piuttosto che del 4%;&nbsp; ed in data odierna sono state inviate agli iscritti appositi avvisi&nbsp; in vista dell`imminente elaborazione del ruolo esattoriale di recupero&nbsp;Si sottolinea peraltro, che la regolarizzazione&nbsp; spontanea&nbsp; comporta anche il grande vantaggio di poter rateizzare il debito maturato e richiedere il certificato di regolarit&agrave; contributiva.&nbsp;&nbsp; La possibilit&agrave; di accedere al Portale di pagamento per sanare la morosit&agrave; sar&agrave; mantenuta fino al 15 novembre prossimo, data di elaborazione del ruolo esattoriale. Dopo tale data sar&agrave; notificata la cartella esattoriale senza ulteriori avvisi da parte della Cipag.&nbsp;Nel pregare di dare comunque la massima diffusione a tale comunicato &#8211; gi&agrave; presente anche sul sito Cipag &#8211; per fornire un ulteriore servizio agli iscritti che eviti loro la ricezione delle citate cartelle esattoriali, si porgono cordiali saluti&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; LA DIREZIONE GENERALE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di seguito si riporta la comunicazione ricevuta in data odierna dalla Direzione Generale della CIPAG&nbsp;di preavviso emissione cartella esattoriale per le irregolarit&agrave; contributive&nbsp;anni 2007 &#8211; 2011, sanabili sul Portale dei Pagamenti entro il 15\/11\/2013:Spettabile Collegio,&nbsp;si ricorda che nell`ambito delle verifiche periodicamente compiute sulle posizioni contributive degli iscritti, la Cipag ha effettuato il controllo sul quinquennio 2007-2011 allo scopo di evitare che la relativa contribuzione si prescriva, rendendo invalidi gli anni ai fini previdenziali.&nbsp;Delle singole posizioni irregolari sono stati informati, lo scorso mese di luglio, tutti gli interessati con dettagliate comunicazioni personalizzate (via pec o posta raccomandata) che li invitavano, nel&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4333"}],"collection":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/comments?post=4333"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/4333\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/media?parent=4333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/categories?post=4333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/tags?post=4333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}