
{"id":12221,"date":"2023-08-07T15:29:54","date_gmt":"2023-08-07T13:29:54","guid":{"rendered":"https:\/\/www.geometrire.it\/collegio\/?p=12221"},"modified":"2023-08-29T15:30:06","modified_gmt":"2023-08-29T13:30:06","slug":"12-09-2023-incontro-con-i-praticanti-di-presentazione-corso-in-preparazione-esame-di-stato-c-o-sede-collegio","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/collegio\/12-09-2023-incontro-con-i-praticanti-di-presentazione-corso-in-preparazione-esame-di-stato-c-o-sede-collegio\/","title":{"rendered":"12\/09\/2023 Incontro con i Praticanti di presentazione Corso in preparazione Esame di Stato c\/o sede Collegio"},"content":{"rendered":"<p>Ai Candidati all\u2019Esame di Stato per l\u2019Abilitazione alla professione di Geometra \u2013 sessione 2023<\/p>\n<p>Con la presente siamo a invitarvi <strong>Marted\u00ec 12 Settembre p.v. dalle ore 14.00 alle ore 18.00<\/strong> all\u2019incontro di <strong>presentazione del\u00a0\u201cCORSO IN PREPARAZIONE ESAME DI STATO &#8211; anno 2023&#8243;<\/strong> e alla sua <strong>1^ lezione <\/strong>che avr\u00e0 come argomento <strong>\u201cOrientamento alla professione, competenze e codice deontologico e tariffe\u201d.<br \/>\n<\/strong>L\u2019incontro si svolger\u00e0 in presenza presso la Sala Conferenze del Collegio Geometri \u2013 Reggio Emilia Via A. Pansa n. 1 (ingresso adiacente al parcheggio, campanello sala riunioni).<br \/>\nSar\u00e0 l\u2019occasione per presentarvi il calendario del corso e fornirvi tutte le informazioni del caso.<br \/>\nAnche se per questo primo appuntamento non \u00e8 richiesta alcuna iscrizione, rimane comunque gradita una vostra conferma di partecipazione.<br \/>\nIn attesa di incontrarvi, porgiamo cordiali saluti.<\/p>\n<p>Il Consigliere delegato<br \/>\ngeom. Pierluigi De Vivo<\/p>\n<p>Collegio Geometri e Geometri Laureati<br \/>\ndella Provincia di Reggio Emilia<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ai Candidati all\u2019Esame di Stato per l\u2019Abilitazione alla professione di Geometra \u2013 sessione 2023 Con la presente siamo a invitarvi Marted\u00ec 12 Settembre p.v. dalle ore 14.00 alle ore 18.00 all\u2019incontro di presentazione del\u00a0\u201cCORSO IN PREPARAZIONE ESAME DI STATO &#8211; anno 2023&#8243; e alla sua 1^ lezione che avr\u00e0 come argomento \u201cOrientamento alla professione, competenze e codice deontologico e tariffe\u201d. L\u2019incontro si svolger\u00e0 in presenza presso la Sala Conferenze del Collegio Geometri \u2013 Reggio Emilia Via A. Pansa n. 1 (ingresso adiacente al parcheggio, campanello sala riunioni). Sar\u00e0 l\u2019occasione per presentarvi il calendario del corso e fornirvi tutte le informazioni&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/12221"}],"collection":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/comments?post=12221"}],"version-history":[{"count":1,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/12221\/revisions"}],"predecessor-version":[{"id":12222,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/posts\/12221\/revisions\/12222"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/media?parent=12221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/categories?post=12221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/collegio\/wp-json\/wp\/v2\/tags?post=12221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}