
{"id":8114,"date":"2009-09-08T00:00:00","date_gmt":"2009-09-07T22:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/associazione\/convegno-15-settembre-2009-reggio-emilia-applicazione-l-r-n-6-del-6-luglio-2009-governo-e-riqualificazione-solidale-del-territorio-locandina\/"},"modified":"2009-09-08T00:00:00","modified_gmt":"2009-09-07T22:00:00","slug":"convegno-15-settembre-2009-reggio-emilia-applicazione-l-r-n-6-del-6-luglio-2009-governo-e-riqualificazione-solidale-del-territorio-locandina","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/convegno-15-settembre-2009-reggio-emilia-applicazione-l-r-n-6-del-6-luglio-2009-governo-e-riqualificazione-solidale-del-territorio-locandina\/","title":{"rendered":"Convegno 15 settembre 2009 &#8211; Reggio Emilia &#8211; Applicazione L. R. n&deg; 6 del 6 Luglio 2009 &#8211; Governo e Riqualificazione solidale del Territorio &#8211; locandina"},"content":{"rendered":null,"protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/8114"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=8114"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/8114\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=8114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=8114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=8114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}