
{"id":7971,"date":"2010-02-09T00:00:00","date_gmt":"2010-02-08T23:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/associazione\/convegno-case-in-legno-ed-in-muratura-caratteristiche-sismiche-ed-energetiche-a-confronto-reggio-emilia-fiera-ecocasa-2010-26022010\/"},"modified":"2010-02-09T00:00:00","modified_gmt":"2010-02-08T23:00:00","slug":"convegno-case-in-legno-ed-in-muratura-caratteristiche-sismiche-ed-energetiche-a-confronto-reggio-emilia-fiera-ecocasa-2010-26022010","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/convegno-case-in-legno-ed-in-muratura-caratteristiche-sismiche-ed-energetiche-a-confronto-reggio-emilia-fiera-ecocasa-2010-26022010\/","title":{"rendered":"Convegno &quot;Case in legno ed in muratura: caratteristiche sismiche ed energetiche a confronto&quot; Reggio Emilia fiera ECOCASA 2010 &#8211; 26\/02\/2010"},"content":{"rendered":"<p>Il Convegno organizzato dal nostro Collegio, si terr&agrave; a Reggio Emilia in data 26 Febbraio p.v. , presso l&#8217;Auditorium della Fiera di Reggio E. in occasione di ECOCASA 2010, a partecipazione gratuita. LA CAPIENZA DELLA SALA E&#8217; ESAURITA &#8211; LE ISCRIZIONI SUCCESSIVE AL 14\/02\/2010, SONO ACCETTATE CON RISERVA E DA CONFERMARE A CURA DELLA SEGRETERIA ORGANIZZATIVA.La registrazione obbligatoria al sito web: <a href=\"http:\/\/www.ecocasa.re.it\/convegni.asp?id=56\">www.ecocasa.re.it<\/a>Il convegno d&agrave; diritto a&nbsp;3 CREDITI FORMATIVI PROFESSIONALI&nbsp;(Regolamento per la Formazione Professionale Continua CNG e GL in vigore dal 01\/01\/2010)<\/p>\n<p><a target='_blank' href='http:\/\/www.geometrire.it\/cms_rc\/allegati\/1355__3315_Convegno_Geometri_bassadef.pdf'>locandina convegno<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Convegno organizzato dal nostro Collegio, si terr&agrave; a Reggio Emilia in data 26 Febbraio p.v. , presso l&#8217;Auditorium della Fiera di Reggio E. in occasione di ECOCASA 2010, a partecipazione gratuita. LA CAPIENZA DELLA SALA E&#8217; ESAURITA &#8211; LE ISCRIZIONI SUCCESSIVE AL 14\/02\/2010, SONO ACCETTATE CON RISERVA E DA CONFERMARE A CURA DELLA SEGRETERIA ORGANIZZATIVA.La registrazione obbligatoria al sito&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/7971"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=7971"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/7971\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=7971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=7971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=7971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}