
{"id":7884,"date":"2010-04-14T00:00:00","date_gmt":"2010-04-13T22:00:00","guid":{"rendered":"http:\/\/www.geometrire.it\/associazione\/convegno-fiscalita-immobiliare-2010-reggio-emilia-21052010-2-cfp\/"},"modified":"2010-04-14T00:00:00","modified_gmt":"2010-04-13T22:00:00","slug":"convegno-fiscalita-immobiliare-2010-reggio-emilia-21052010-2-cfp","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/convegno-fiscalita-immobiliare-2010-reggio-emilia-21052010-2-cfp\/","title":{"rendered":"Convegno &quot;FISCALITA&#8217; IMMOBILIARE 2010&quot; Reggio Emilia 21\/05\/2010 &#8211; (2 CFP)"},"content":{"rendered":"<p>Il&nbsp;Convegno organizzato&nbsp;dal&nbsp;nostro&nbsp;Collegio con Associazione della&nbsp;Propriet&agrave; Edilizia della&nbsp;Prov. di Reggio Emilia&nbsp;,&nbsp;si terr&agrave;&nbsp;presso la nostra sede in data&nbsp;21&nbsp;maggio&nbsp;p.v., a partecipazione gratuita, iscrizione obbligatoria. La partecipazione al Convegno d&agrave; diritto a&nbsp;2 CREDITI FORMATIVI PROFESSIONALI&nbsp;(Regolamento per la Formazione Professionale Continua CNG e GL in vigore dal 01\/01\/2010).<\/p>\n<p><a target='_blank' href='http:\/\/www.geometrire.it\/cms_rc\/allegati\/1495__4540_Convegno_Fiscalit_Immobiliare_21_05_2010.pdf'>Locandina<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il&nbsp;Convegno organizzato&nbsp;dal&nbsp;nostro&nbsp;Collegio con Associazione della&nbsp;Propriet&agrave; Edilizia della&nbsp;Prov. di Reggio Emilia&nbsp;,&nbsp;si terr&agrave;&nbsp;presso la nostra sede in data&nbsp;21&nbsp;maggio&nbsp;p.v., a partecipazione gratuita, iscrizione obbligatoria. La partecipazione al Convegno d&agrave; diritto a&nbsp;2 CREDITI FORMATIVI PROFESSIONALI&nbsp;(Regolamento per la Formazione Professionale Continua CNG e GL in vigore dal 01\/01\/2010). Locandina<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/7884"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=7884"}],"version-history":[{"count":0,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/7884\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=7884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=7884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=7884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}