
{"id":18138,"date":"2025-09-03T10:34:34","date_gmt":"2025-09-03T08:34:34","guid":{"rendered":"https:\/\/www.geometrire.it\/associazione\/?p=18138"},"modified":"2025-09-03T10:56:14","modified_gmt":"2025-09-03T08:56:14","slug":"corso-ifts-green-building-tecnico-bim-in-rilievo-digitale-riqualificazione-energetica-degli-edifici-c-o-res-x-praticanti-e-professionisti","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/corso-ifts-green-building-tecnico-bim-in-rilievo-digitale-riqualificazione-energetica-degli-edifici-c-o-res-x-praticanti-e-professionisti\/","title":{"rendered":"Corso IFTS \u201cGreen Building &#8211; Tecnico BIM in Rilievo Digitale Riqualificazione Energetica degli Edifici\u201d c\/o RES (x Praticanti e Professionisti)"},"content":{"rendered":"<p><strong>CORSO GRATUITO<br \/>\n<\/strong><strong>GREEN BUILDING \u2013 TECNICO BIM IN RILIEVO DIGITALE E RIQUALIFICAZIONE ENERGETICA DEGLI EDIFICI<\/strong><\/p>\n<p>Operazione Rif. PA 2025-24014\/RER approvata con DGR n. 1238 del 28\/07\/2025 cofinanziata dal Fondo Sociale Europeo Plus 2021\/2027 e Regione Emilia-Romagna.<br \/>\nIl Tecnico BIM esperto in rilievo digitale e riqualificazione energetica degli edifici \u00e8 un professionista in grado di utilizzare strumenti tecnologici innovativi per migliorare l\u2019efficienza e l\u2019accuratezza dei processi edilizi. Questa figura professionale fa uso del software BIM (Building Information Modeling) per la progettazione integrata; l\u2019impiego del drone per rilievi topografici e ispezioni edilizie; l\u2019utilizzo di termocamera per la diagnosi energetica degli edifici. Ai partecipanti saranno inoltre introdotti i principi dell\u2019intelligenza artificiale applicata alla gestione dei dati edilizi, migliorando l\u2019efficienza e l\u2019accuratezza dei dati, report, etc\u2026 Grazie ad esercitazioni pratiche e progetti reali, acquisisce competenze tecniche specifiche che gli permettono di affrontare con successo le sfide del settore delle costruzioni.<\/p>\n<p><strong>Chi pu\u00f2 partecipare:<\/strong> Giovani e adulti, occupati e non occupati, residenti e\/o domiciliati in Emilia-Romagna, in possesso almeno del diploma di Scuola Media Superiore, e\/o Laurea.<\/p>\n<p>L\u2019accesso \u00e8 esteso, secondo la normativa vigente, anche a:<br \/>\n\u2013 soggetti ammessi al quinto anno dei percorsi liceali (D.Lgs. 226\/2005, art. 2, c.5);<br \/>\n\u2013 persone non diplomate, previa certificazione delle competenze acquisite in ambito scolastico, formativo o lavorativo, ai sensi del D.M. 139\/2007;<br \/>\n\u2013 titolari di diploma professionale conseguito al termine del quarto anno di IeFP, in coerenza con le correlazioni previste tra IeFP e specializzazioni IFTS (Allegato B del Decreto MIUR-MLPS 7\/2\/2013 n.91, es. \u201cTecnico Edile\u201d).<br \/>\n\u00c8 ammessa la partecipazione di apprendisti per il conseguimento della specializzazione tecnica superiore, in base al D.Lgs.\u00a0 81\/2015 art. 43 e DGR 963\/2016.<br \/>\nIl corso si intende ovviamente aperto sia a uomini che a donne.<br \/>\nIl corso permette a diplomati e neodiplomati di entrare nel modo del lavoro con l\u2019acquisizione di competenze professionalizzanti o di potenziare la preparazione per l\u2019accesso all\u2019universit\u00e0. Per laureati, neolaureati e professionisti (anche con P.IVA), invece, permette l\u2019acquisizione di crediti formativi (professionali e\/o universitari) e di conseguire la specializzazione tecnica adeguata a riqualificare e aggiornare le competenze in edilizia e costruzioni.<\/p>\n<p><strong>Durata:<\/strong> Il corso prevede 800 ore &#8211; Aula 440 ore, Project Work 80 ore, Stage 280 ore presso aziende o studi professionali.<\/p>\n<p><strong>CREDITI IN INGRESSO:<\/strong>\u00a0per i professionisti che gi\u00e0 operano nel settore, sono previsti Crediti Formativi che riducono la frequenza del percorso<br \/>\nLe lezioni si svolgeranno in presenza e parte online con modalit\u00e0 sincrona, previste visite in cantiere e partecipazione a fiere ed eventi del settore nazionali e internazionali come <strong>Klimahouse a Bolzano, MCE Milano.<\/strong><br \/>\nI software utilizzati saranno BIM Revit, Edilclima\/Termolog e Realityscan 2.0;<br \/>\nIl project work prevede lo sviluppo di un progetto di diagnosi e riqualificazione energetica basato su un caso reale.<br \/>\nCon lo stage i partecipanti sono inseriti in contesti lavorativi per sperimentare il ruolo sul campo e seguire progetti di riqualificazione in aziende o studi professionali.<br \/>\nPer professionisti e occupati \u00e8 possibile attivare progetti di stage individuali se l\u2019occupazione \u00e8 coerente con il percorso<br \/>\nIl percorso rilascia:<br \/>\n&#8211; Crediti formativi universitari;<br \/>\n&#8211; Crediti per la partecipazione al corso da Certificatore Energetico;<br \/>\n&#8211; Crediti per la partecipazione all\u2019esame del PATENTINO DRONE OPEN A1\/A3<br \/>\nI geometri possono utilizzare i 12 mesi di corso come periodo di praticantato (previa iscrizione al Registro dei Praticanti).<br \/>\n<strong>Titolo rilasciato:<\/strong> Al superamento dell\u2019esame finale viene rilasciato il Certificato di Specializzazione Tecnica Superiore in Tecniche Innovative per l\u2019Edilizia previsto dalla normativa nazionale.<br \/>\n<strong>Iscrizione e selezione<\/strong>: Compilando l&#8217;apposito modulo di candidatura e partecipando alla selezione.<br \/>\n<strong>Chiusura iscrizioni: 11 novembre 2025<br \/>\n<\/strong><strong>Avvio previsto: 26 novembre 2025<br \/>\n<\/strong>Il corso \u00e8 GRATUITO. I progetti sono infatti realizzati grazie ai Fondi europei della Regione Emilia-Romagna(Operazione Rif. PA\u00a02025-24014\/RER approvata con DGR n. 1238 del 28\/07\/2025 cofinanziata dal Fondo Sociale Europeo Plus 2021\/2027 e Regione Emilia-Romagna)<\/p>\n<p><strong>OPENDAY<\/strong>\u00a0di presentazione del percorso:<br \/>\n17 SETTEMBRE 2025<br \/>\n15 OTTOBRE 2025<br \/>\nPresso la sede della Scuola Edile e online. La partecipazione \u00e8 GRATUITA.<\/p>\n<p><strong>Maggiori informazioni<br \/>\n<\/strong>0522-500450<br \/>\n<a href=\"mailto:superiore@res.re.it\">superiore@res.re.it<\/a><\/p>\n<p>Scheda del corso su sito: <a href=\"https:\/\/www.res.re.it\/edizioni\/GREEN_BUILDING_-_TECNICO_BIM_IN_RILIEVO_DIGITALE_E_RIQUALIFICAZIONE_ENERGETICA_DEGLI_EDIFICI\/10004\">https:\/\/www.res.re.it\/edizioni\/GREEN_BUILDING_-_TECNICO_BIM_IN_RILIEVO_DIGITALE_E_RIQUALIFICAZIONE_ENERGETICA_DEGLI_EDIFICI\/10004<\/a><\/p>\n<p>In allegato:<br \/>\n&#8211; brochure informativa\u00a0 <a href=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2025\/09\/Rifpa-2025-24014-SCHEDA-CORSO-RER.pdf\">Rifpa 2025-24014- SCHEDA CORSO RER<\/a><br \/>\n&#8211; modulo di iscrizione\u00a0 <a href=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2025\/09\/Rifpa-2025-24014-SCHEDA-CANDIDATURA-COMPLETA__.pdf\">Rifpa 2025 -24014 SCHEDA CANDIDATURA COMPLETA__<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2025\/09\/Green-building_Scuola-Edile-RE.png\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-18141\" src=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2025\/09\/Green-building_Scuola-Edile-RE.png\" alt=\"\" width=\"1808\" height=\"1808\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORSO GRATUITO GREEN BUILDING \u2013 TECNICO BIM IN RILIEVO DIGITALE E RIQUALIFICAZIONE ENERGETICA DEGLI EDIFICI Operazione Rif. PA 2025-24014\/RER approvata con DGR n. 1238 del 28\/07\/2025 cofinanziata dal Fondo Sociale Europeo Plus 2021\/2027 e Regione Emilia-Romagna. Il Tecnico BIM esperto in rilievo digitale e riqualificazione energetica degli edifici \u00e8 un professionista in grado di utilizzare strumenti tecnologici innovativi per migliorare&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18138"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=18138"}],"version-history":[{"count":1,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18138\/revisions"}],"predecessor-version":[{"id":18142,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18138\/revisions\/18142"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=18138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=18138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=18138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}