
{"id":18099,"date":"2025-08-01T15:13:08","date_gmt":"2025-08-01T13:13:08","guid":{"rendered":"https:\/\/www.geometrire.it\/associazione\/?p=18099"},"modified":"2025-08-25T14:38:58","modified_gmt":"2025-08-25T12:38:58","slug":"26-09-2025-seminario","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/26-09-2025-seminario\/","title":{"rendered":"25\/09\/2025 Seminario &#8220;Le soluzioni di illuminazione di Ledvance e dimensionamento illuminotecnico con Dialux Evo&#8221;"},"content":{"rendered":"<p>LEDVANCE con il patrocinio di Ordine Architetti, Ordine Periti Industriali e Collegio Geometri organizzano <strong>Seminario &#8220;Le soluzioni di illuminazione di Ledvance e dimensionamento illuminotecnico con Dialux Evo&#8221;<\/strong><\/p>\n<p><strong>Data:<\/strong> Gioved\u00ec 25 settembre 2025<br \/>\n<strong>Orario:<\/strong> dalle ore 14:30 alle ore 17:30<br \/>\n<strong>Modalit\u00e0 di svolgimento<\/strong>: in Presenza c\/o Remilia Hotel in Reggio Emilia<br \/>\n<strong>Locandina:<\/strong> <a href=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2025\/08\/2025_09_25-Locandina-Seminario-Le-soluzioni-di-illuminazione.pdf\">2025_09_25 Locandina Seminario Le soluzioni di illuminazione<\/a><br \/>\n<strong>Quota di partecipazione:<\/strong>\u00a0gratuito<br \/>\n<strong>Iscrizione: <\/strong>vedi modalit\u00e0 riportate sulla locandina<\/p>\n<p>Ai Geometri partecipanti verranno assegnati <strong>n. 3 CFP<\/strong>\u00a0(Regolamento per la Formazione Professionale Continua CNGeGL in vigore dal 31\/05\/2021).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEDVANCE con il patrocinio di Ordine Architetti, Ordine Periti Industriali e Collegio Geometri organizzano Seminario &#8220;Le soluzioni di illuminazione di Ledvance e dimensionamento illuminotecnico con Dialux Evo&#8221; Data: Gioved\u00ec 25 settembre 2025 Orario: dalle ore 14:30 alle ore 17:30 Modalit\u00e0 di svolgimento: in Presenza c\/o Remilia Hotel in Reggio Emilia Locandina: 2025_09_25 Locandina Seminario Le soluzioni di illuminazione Quota di&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18099"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=18099"}],"version-history":[{"count":4,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18099\/revisions"}],"predecessor-version":[{"id":18121,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18099\/revisions\/18121"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=18099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=18099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=18099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}