
{"id":18031,"date":"2025-06-10T10:41:51","date_gmt":"2025-06-10T08:41:51","guid":{"rendered":"https:\/\/www.geometrire.it\/associazione\/?p=18031"},"modified":"2025-07-04T15:39:22","modified_gmt":"2025-07-04T13:39:22","slug":"03-07-2025-corso-metti-ordine-nella-tua-attivita-sviluppando-intelligenza-manageriale","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/03-07-2025-corso-metti-ordine-nella-tua-attivita-sviluppando-intelligenza-manageriale\/","title":{"rendered":"03\/07\/2025 Corso &#8220;Metti ordine nella tua attivit\u00e0 sviluppando intelligenza manageriale&#8221;"},"content":{"rendered":"<p>Societ\u00e0 benefit &#8220;Intelligenza Manageriale\u201d in collaborazione con Collegio e Associazione Geometri, organizza<strong> Corso &#8220;Metti ordine nella tua attivit\u00e0 sviluppando intelligenza manageriale&#8221;<\/strong><\/p>\n<p><strong>Data:<\/strong> Gioved\u00ec 3 Luglio 2025<br \/>\n<strong>Orario:<\/strong> dalle ore 9:30 alle ore 12:30<br \/>\n<strong>Modalit\u00e0 di svolgimento<\/strong>: in Presenza c\/o Sala Conferenze Collegio Geometri &#8211; Reggio Emilia Via A. Pansa n. 1<br \/>\n<strong>Locandina:<\/strong> <a href=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2025\/06\/Locandina-03_07_2025-Corso-Intelligenza-Manageriale.pdf\">Locandina 03_07_2025 Corso Intelligenza Manageriale<\/a><br \/>\n<strong>Quota di partecipazione:<\/strong> gratuito<br \/>\n<strong>Iscrizione:<\/strong> modalit\u00e0 indicate nella locandina &#8211; link <a href=\"https:\/\/register.gotowebinar.com\/register\/1251652598974668890\">https:\/\/register.gotowebinar.com\/register\/1251652598974668890<\/a><\/p>\n<p>Ai Geometri partecipanti con frequenza del 100% verranno assegnati <strong>n. 3 CFP<\/strong>\u00a0(Regolamento per la Formazione Professionale Continua CNGeGL in vigore dal 31\/05\/2021).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Societ\u00e0 benefit &#8220;Intelligenza Manageriale\u201d in collaborazione con Collegio e Associazione Geometri, organizza Corso &#8220;Metti ordine nella tua attivit\u00e0 sviluppando intelligenza manageriale&#8221; Data: Gioved\u00ec 3 Luglio 2025 Orario: dalle ore 9:30 alle ore 12:30 Modalit\u00e0 di svolgimento: in Presenza c\/o Sala Conferenze Collegio Geometri &#8211; Reggio Emilia Via A. Pansa n. 1 Locandina: Locandina 03_07_2025 Corso Intelligenza Manageriale Quota di partecipazione:&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18031"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=18031"}],"version-history":[{"count":1,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18031\/revisions"}],"predecessor-version":[{"id":18033,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/18031\/revisions\/18033"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=18031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=18031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=18031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}