
{"id":17987,"date":"2025-05-12T15:52:58","date_gmt":"2025-05-12T13:52:58","guid":{"rendered":"https:\/\/www.geometrire.it\/associazione\/?p=17987"},"modified":"2025-05-12T16:00:28","modified_gmt":"2025-05-12T14:00:28","slug":"da-giugno-2025-corsi-finanziati-progetto-vic-valorizzazione-e-innovazione-delle-competenze-del-professionista","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/da-giugno-2025-corsi-finanziati-progetto-vic-valorizzazione-e-innovazione-delle-competenze-del-professionista\/","title":{"rendered":"da giugno 2025 &#8211; Corsi finanziati Progetto VIC: valorizzazione e Innovazione delle Competenze del professionista"},"content":{"rendered":"<p><strong>CORSI VIC<\/strong><\/p>\n<p>IFOA ha\u00a0 ricevuto finanziamento della Regione Emilia Romagna relativo al progetto <a href=\"https:\/\/www.ifoa.it\/servizi\/corsi-di-formazione\/corsi-a-catalogo\/corsi-gratuiti-per-liberi-professionisti\/\">\u201cVIC: valorizzazione e Innovazione delle Competenze del professionista\u201d<\/a><\/p>\n<p>IFOA ha predisposto le prime edizioni per 5 dei corsi approvati, seguiranno nelle prossime settimane le calendarizzazioni degli altri corsi previsti dal progetto.<\/p>\n<p>I corsi in partenza, a cui \u00e8 gi\u00e0 possibile iscriversi, sono:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ifoa.it\/corsi\/ca-management-organizzazione-qualita-corso-project-management-metodologie-e-strumenti\/\">Project Management metodologie e strumenti<\/a><\/li>\n<li><a href=\"https:\/\/www.ifoa.it\/corsi\/ca-risorse_umane-corso-benessere-aziendale-e-retention-dei-collaboratori\/\">Benessere aziendale e retention dei collaboratori<\/a><\/li>\n<li><a href=\"https:\/\/www.ifoa.it\/corsi\/ca-marketing-corso-sulla-comunicazione-efficace-e-gestione-delle-relazioni\/\">Comunicazione Efficace e gestione delle relazioni<\/a><\/li>\n<li><a href=\"https:\/\/www.ifoa.it\/corsi\/ca-ambiente_energia-corso-sulla-gestione-delle-comunita-energetiche\/\">La gestione delle comunit\u00e0 energetiche<\/a><\/li>\n<li><a href=\"https:\/\/www.ifoa.it\/corsi\/ca-management-organizzazione-qualita-corso-lean-office-ottimizzazione-delle-attivita-gestione-del-tempo\/\">Lean Office: ottimizzazione delle attivit\u00e0 e gestione del tempo<\/a><\/li>\n<\/ul>\n<p>La partecipazione ai Corsi d\u00e0 diritto a CFP per i Geometri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORSI VIC IFOA ha\u00a0 ricevuto finanziamento della Regione Emilia Romagna relativo al progetto \u201cVIC: valorizzazione e Innovazione delle Competenze del professionista\u201d IFOA ha predisposto le prime edizioni per 5 dei corsi approvati, seguiranno nelle prossime settimane le calendarizzazioni degli altri corsi previsti dal progetto. I corsi in partenza, a cui \u00e8 gi\u00e0 possibile iscriversi, sono: Project Management metodologie e strumenti&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/17987"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=17987"}],"version-history":[{"count":2,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/17987\/revisions"}],"predecessor-version":[{"id":17989,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/17987\/revisions\/17989"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=17987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=17987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=17987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}