
{"id":16554,"date":"2023-03-30T17:25:59","date_gmt":"2023-03-30T15:25:59","guid":{"rendered":"https:\/\/www.geometrire.it\/associazione\/?p=16554"},"modified":"2023-04-12T19:02:27","modified_gmt":"2023-04-12T17:02:27","slug":"convenzione-con-geo-network-s-r-l-licenze-software-professionali-e-corsi-di-formazione","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/convenzione-con-geo-network-s-r-l-licenze-software-professionali-e-corsi-di-formazione\/","title":{"rendered":"Convenzione con Geo Network S.r.l. &#8211; Licenze software professionali e corsi di formazione"},"content":{"rendered":"<p>Il Collegio ha rinnovato la convenzione con Geo Network S.r.l. per l&#8217;acquisto, a condizioni di favore riservate ai propri iscritti, di licenze software professionali e corsi di formazione.<\/p>\n<p>Dal 1996, la S.r.l. Geo Network Srl, con sede a Sarzana (SP), sviluppa software gestionali per l&#8217;edilizia e lo studio professionale garantendo semplificazione, qualit\u00e0 e massima efficienza al lavoro di liberi professionisti quali i Geometri.<\/p>\n<p>Inoltre, attraverso la Divisione Formazione, Geo Network S.r.l. offre un catalogo di corsi accreditati con CFP (in aula &#8211; webinar &#8211; e-learning), in materie di grande interesse per la nostra Categoria quali: Successioni, Detrazioni fiscali in edilizia, Stime Immobiliari, Urbanistica e Paesaggistica, Certificazione Energetica, Computo e Contabilit\u00e0 dei Lavori, Sicurezza nei cantieri e Gestione condom\u00ecni.<\/p>\n<p>Le condizioni di maggior favore riservati ai Geometri iscritti all&#8217;Albo di Reggio Emilia si concretizzano in:<\/p>\n<ul>\n<li>S<strong>conto fisso del 15%<\/strong> rispetto ai prezzi pubblicati sul sito web <a href=\"https:\/\/www.geonetwork.it\/\">www.geonetwork.it<\/a> per l&#8217;acquisto di singole licenze d&#8217;uso di software (no aggiornamenti e canoni) e\/o per l&#8217;acquisto di corsi di formazione o altri servizi a pagamento offerti da Geo Network;<\/li>\n<li>Per <strong>giovani Geometri,<\/strong> ovvero praticanti e iscritti under 36*, <strong>sconto fisso del 30%<\/strong> rispetto ai prezzi pubblicati sul sito web <a href=\"https:\/\/www.geonetwork.it\/\">www.geonetwork.it<\/a> per l&#8217;acquisto di singole licenze d&#8217;uso di software (no aggiornamenti e canoni) e\/o per l&#8217;acquisto di corsi di formazione o altri servizi a pagamento offerti da Geo Network.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 * L&#8217;et\u00e0 andr\u00e0 dimostrata attraverso l&#8217;invio via email a Geo Network del proprio documento d&#8217;identit\u00e0.<\/li>\n<\/ul>\n<p>Il codice sconto esclusivo, applicabile direttamente sul sito web <a href=\"https:\/\/www.geonetwork.it\/\">www.geonetwork.it<\/a> o su ordini trasmessi via email \u00e8: <strong>GEOMREGGIOEMILIA21<\/strong><\/p>\n<p>Alleghiamo di seguito:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2023\/04\/Utilizzo-codice-di-sconto-Reggio-Emilia.pdf\">Guida all&#8217;utilizzo del codice sconto<\/a><\/li>\n<li><a href=\"https:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2023\/04\/Benefici-convenzioni-Collegio-ReggioEmilia.pdf\">Brochure riepilogativa servizi e vantaggi riservati<\/a><\/li>\n<\/ul>\n<p>Per visualizzare i prezzi dei prodotti Geo Network collegarsi al sito <a href=\"https:\/\/www.geonetwork.it\/\">www.geonetwork.it<\/a>, sezione Acquista<\/p>\n<p style=\"text-align: center;\"><strong>CONVENZIONE VALIDA SINO AL 31\/12\/2023<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Collegio ha rinnovato la convenzione con Geo Network S.r.l. per l&#8217;acquisto, a condizioni di favore riservate ai propri iscritti, di licenze software professionali e corsi di formazione. Dal 1996, la S.r.l. Geo Network Srl, con sede a Sarzana (SP), sviluppa software gestionali per l&#8217;edilizia e lo studio professionale garantendo semplificazione, qualit\u00e0 e massima efficienza al lavoro di liberi professionisti&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[38,51,110],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/16554"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=16554"}],"version-history":[{"count":8,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/16554\/revisions"}],"predecessor-version":[{"id":16564,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/16554\/revisions\/16564"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=16554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=16554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=16554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}