
{"id":15062,"date":"2021-04-13T09:44:25","date_gmt":"2021-04-13T07:44:25","guid":{"rendered":"https:\/\/www.geometrire.it\/associazione\/?p=15062"},"modified":"2021-04-19T17:24:39","modified_gmt":"2021-04-19T15:24:39","slug":"giovedi-15-04-2021-chiusura-uffici-di-segreteria","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/giovedi-15-04-2021-chiusura-uffici-di-segreteria\/","title":{"rendered":"Gioved\u00ec 15\/04\/2021 &#8211; Chiusura uffici di Segreteria"},"content":{"rendered":"<p>Si comunica che gli Uffici di Segreteria\u00a0rimarranno chiusi Gioved\u00ec 15\/04\/2021\u00a0 per corso di aggiornamento del personale di Segreteria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che gli Uffici di Segreteria\u00a0rimarranno chiusi Gioved\u00ec 15\/04\/2021\u00a0 per corso di aggiornamento del personale di Segreteria.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/15062"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=15062"}],"version-history":[{"count":1,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/15062\/revisions"}],"predecessor-version":[{"id":15063,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/15062\/revisions\/15063"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=15062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=15062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=15062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}