
{"id":14290,"date":"2020-03-18T10:42:38","date_gmt":"2020-03-18T09:42:38","guid":{"rendered":"http:\/\/www.geometrire.it\/associazione\/?p=14290"},"modified":"2020-05-13T13:37:36","modified_gmt":"2020-05-13T11:37:36","slug":"18-03-2020-comunicazione-del-presidente-collegio-testo-d-l-n-18-del-17-03-2020","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/18-03-2020-comunicazione-del-presidente-collegio-testo-d-l-n-18-del-17-03-2020\/","title":{"rendered":"18\/03\/2020 Comunicazione del Presidente Collegio &#8211; testo D.L. n. 18 del 17\/03\/2020"},"content":{"rendered":"<p>A tutti gli Iscritti<\/p>\n<p>Carissimi Colleghi,<br \/>\nper le vie brevi vi allego il testo della Gazzetta Ufficiale\u00a0del Decreto Legge n. 18 del 17\/03\/2020, appena pubblicato e dove gli articoli di nostro immediato utilizzo sono il 27 per aiuti alle P. IVA che per\u00f2 sostanzialmente ci esclude&#8230;., l&#8217;Art. 103 per differimento termini amministrativi\u00a0 vari a noi molto utile e l&#8217;Art. 44 per fondo aiuto lavoratori a noi riferibile ma che alla luce dei numeri credo ci dar\u00e0 solo delle briciole con futuri decreti\u2026.<br \/>\nIeri sera ho partecipato a video conferenza tra Presidenti di CNG, Cassa e Collegi Emilia Romagna e Marche per valutare le strategie comuni di Cassa e CNG in aiuto agli iscritti, ambito nel quale si stanno attivando, cos\u00ec come anche noi stiamo facendo con determinazione a livello locale per garantire operativit\u00e0 e sostegno immediato e per il futuro.<br \/>\nDi ci\u00f2 vi faremo sapere appena saremo in grado di poter deliberare gi\u00e0 dalle prossime ore ed a tal fine sono ovviamente ben accetti suggerimenti ed idee da parte di tutti.<br \/>\nBuona giornata.<\/p>\n<p>Il Presidente<br \/>\ngeom. Francesco Spallanzani<\/p>\n<p>Allegato: <a href=\"http:\/\/www.geometrire.it\/collegio\/wp-content\/uploads\/sites\/5\/2020\/03\/GU-DL-17.03.2020-n1-8.pdf\">GU DL 17.03.2020 n1 8<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tutti gli Iscritti Carissimi Colleghi, per le vie brevi vi allego il testo della Gazzetta Ufficiale\u00a0del Decreto Legge n. 18 del 17\/03\/2020, appena pubblicato e dove gli articoli di nostro immediato utilizzo sono il 27 per aiuti alle P. IVA che per\u00f2 sostanzialmente ci esclude&#8230;., l&#8217;Art. 103 per differimento termini amministrativi\u00a0 vari a noi molto utile e l&#8217;Art. 44&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/14290"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=14290"}],"version-history":[{"count":1,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/14290\/revisions"}],"predecessor-version":[{"id":14291,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/14290\/revisions\/14291"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=14290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=14290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=14290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}