
{"id":12113,"date":"2018-02-02T17:02:00","date_gmt":"2018-02-02T16:02:00","guid":{"rendered":"http:\/\/www.geometrire.it\/associazione\/?p=12113"},"modified":"2018-02-02T17:05:43","modified_gmt":"2018-02-02T16:05:43","slug":"corso-base-per-mediatori-professionisti-modena-dal-19022018","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/corso-base-per-mediatori-professionisti-modena-dal-19022018\/","title":{"rendered":"Corso base per mediatori professionisti &#8211; Modena dal 19\/02\/2018"},"content":{"rendered":"<p>EFIM\u00a0Modena (ente di formazione interdisciplinare), avvalendosi dell&#8217;ente di formazione\u00a0DISPUTE RESOLUTION,\u00a0organizza presso il Collegio Geometri e Geometri Laureati della Provincia di Modena il \u201cCORSO BASE\u00a0PER MEDIATORI PROFESSIONISTI\u201d della durata di n.\u00a050 ore,\u00a0come da allegata informativa, completa di modulo d&#8217;iscrizione.<\/p>\n<p><a href=\"http:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2018\/02\/Modena_Corso-base-mediatore-50-ore.pdf\">Informativa, programma corso e modulo d&#8217;iscrizione<\/a><\/p>\n<p>Ai partecipanti Geometri con frequenza del 100% verranno attribuiti n.50 \u00a0crediti formativi<\/p>\n<p>Per ogni ulteriore informazione contattare\u00a0direttamente la Segreteria EFIM c\/o il\u00a0Collegio Geometri di Modena tel 059 343585<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EFIM\u00a0Modena (ente di formazione interdisciplinare), avvalendosi dell&#8217;ente di formazione\u00a0DISPUTE RESOLUTION,\u00a0organizza presso il Collegio Geometri e Geometri Laureati della Provincia di Modena il \u201cCORSO BASE\u00a0PER MEDIATORI PROFESSIONISTI\u201d della durata di n.\u00a050 ore,\u00a0come da allegata informativa, completa di modulo d&#8217;iscrizione. Informativa, programma corso e modulo d&#8217;iscrizione Ai partecipanti Geometri con frequenza del 100% verranno attribuiti n.50 \u00a0crediti formativi Per ogni ulteriore informazione&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/12113"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=12113"}],"version-history":[{"count":3,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/12113\/revisions"}],"predecessor-version":[{"id":12117,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/12113\/revisions\/12117"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=12113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=12113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=12113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}