
{"id":11980,"date":"2017-11-08T12:02:21","date_gmt":"2017-11-08T11:02:21","guid":{"rendered":"http:\/\/www.geometrire.it\/associazione\/?p=11980"},"modified":"2017-11-30T12:03:51","modified_gmt":"2017-11-30T11:03:51","slug":"com-8-condominio-fisco-immobiliare-informa-fabbricato-non-strumentale-il-55-va-disconosciuto-subito","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/com-8-condominio-fisco-immobiliare-informa-fabbricato-non-strumentale-il-55-va-disconosciuto-subito\/","title":{"rendered":"Com. 8 Condominio, Fisco immobiliare \u2013 informa &#8220;Fabbricato non strumentale: il 55% va disconosciuto subito&#8221;"},"content":{"rendered":"<p><em><u><span style=\"color: #676767;\">LA COMMISSIONE\u00a08 \u201cCONDOMINIO \u2013 FISCO IMMOBILIARE\u201d INFORMA<\/span><\/u><\/em><\/p>\n<p><strong>Fabbricato non strumentale: il 55% va disconosciuto subito<\/strong><\/p>\n<p>Il Fisco non pu\u00f2 disconoscere la titolarit\u00e0 dell\u2019ecobonus al 55% quando controlla una delle dichiarazioni successive a quella in cui le spese sono state sostenute. Tanto afferma la sentenza della Ctp di Milano 5397\/23\/17 (presidente Zamagni, relatore Contini), risolvendo a favore del contribuente il contenzioso tra una societ\u00e0 immobiliare e le Entrate. La detrazione del 55% delle spese per gli interventi di risparmio energetico (prevista dall\u2019articolo 1, commi 344 e seguenti della legge 296\/2006, di cui \u00e8 in arrivo la proroga anche per il 2018 con la prossima legge di Bilancio) si \u00e8 rivelata uno dei benefici fiscali maggiormente graditi dai contribuenti, come dimostrano i 300mila interventi realizzati nel 2017 (si veda il Quadro di sintesi preliminare dei dati del triennio 2015-2017, reperibile sul sito dell\u2019Enea). Nel caso esaminato dai giudici, una societ\u00e0 immobiliare aveva sostenuto nel 2009 delle spese per la riqualificazione energetica di alcuni immobili strumentali. Nel giugno del 2015 la societ\u00e0 ha ricevuto dalle Entrate una comunicazione di irregolarit\u00e0, conseguente a un controllo da articolo 36-ter sul modello Unico 2012, con cui si disconosceva la spettanza della detrazione in quanto non era stata documentata la natura strumentale dell\u2019immobile. Tesi bocciata dai giudici milanesi, secondo i quali la verifica dei presupposti essenziali per il godimento del beneficio fiscale va essere attuata dagli uffici fiscali nell\u2019ambito dell\u2019attivit\u00e0 di controllo formale della dichiarazione dei redditi dell\u2019anno in cui la prima quota di detrazione viene esposta (nel caso specifico, il 2009, ormai non pi\u00f9 accertabile nel 2015). Essendo, infatti, prevista la detraibilit\u00e0 delle spese durante un arco temporale ben preciso e con determinati limiti di quota gi\u00e0 prefissati dal legislatore, la non spettanza del beneficio fiscale non potr\u00e0 che venire accertata con riferimento all\u2019annualit\u00e0 in cui il presupposto dell\u2019agevolazione si \u00e8 realizzato. Tale preclusione, specifica il collegio, opera solo in caso di mancato riconoscimento della detrazione per l\u2019assenza di un elemento costitutivo del beneficio fiscale e non anche nel caso di disconoscimento della quota parte della detrazione riportata erroneamente nel suo ammontare nelle dichiarazioni successive. Quindi, in relazione a Unico 2012, l\u2019ufficio avrebbe potuto contestare &#8211; ad esempio &#8211; che era stata riportata una cifra superiore a quella indicata nel modello dell\u2019anno precedente. Sicch\u00e9 la mancata rettifica da parte dell\u2019ufficio fiscale della dichiarazione dei redditi relativa all\u2019anno in cui il credito \u00e8 sorto, ovvero si sono verificati i presupposti costitutivi dell\u2019agevolazione fiscale, preclude l\u2019autonoma valutazione della denuncia fiscale relativa all\u2019annualit\u00e0 successiva, essendosi cristallizzato il diritto di credito al momento dell\u2019esposizione in dichiarazione della prima quota di spesa detratta. Si tratta di un principio consolidato in giurisprudenza (si vedano le sentenze di Cassazione 7492\/2016, 14805\/15 e 9339\/2012), che non sempre tuttavia gli uffici applicano alla materia delle detrazioni per il recupero edilizio e il risparmio energetico.<\/p>\n<p><em><span style=\"color: #676767;\">Commissione\u00a08 \u201cCondominio \u2013 Fisco Immobiliare\u201d<br \/>\n<\/span><\/em><em>geom. Maurizio Verdi<br \/>\n<\/em>Collegio e Associazione Geometri<span class=\"Apple-converted-space\">\u00a0<\/span><br \/>\ndella Provincia di Reggio Emilia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA COMMISSIONE\u00a08 \u201cCONDOMINIO \u2013 FISCO IMMOBILIARE\u201d INFORMA Fabbricato non strumentale: il 55% va disconosciuto subito Il Fisco non pu\u00f2 disconoscere la titolarit\u00e0 dell\u2019ecobonus al 55% quando controlla una delle dichiarazioni successive a quella in cui le spese sono state sostenute. Tanto afferma la sentenza della Ctp di Milano 5397\/23\/17 (presidente Zamagni, relatore Contini), risolvendo a favore del contribuente il contenzioso&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[77],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/11980"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=11980"}],"version-history":[{"count":1,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/11980\/revisions"}],"predecessor-version":[{"id":11981,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/11980\/revisions\/11981"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=11980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=11980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=11980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}