
{"id":10936,"date":"2016-12-16T09:32:39","date_gmt":"2016-12-16T08:32:39","guid":{"rendered":"http:\/\/www.geometrire.it\/associazione\/?p=10936"},"modified":"2017-01-09T10:55:07","modified_gmt":"2017-01-09T09:55:07","slug":"chiusura-uffici-di-segreteria-per-ferie","status":"publish","type":"post","link":"https:\/\/www.geometrire.it\/associazione\/chiusura-uffici-di-segreteria-per-ferie\/","title":{"rendered":"AUGURI DI BUONE FESTE &#8211; Chiusura Uffici di Segreteria"},"content":{"rendered":"<p><strong><em><span style=\"color: #ff0000;\">I Consigli Direttivi di Collegio e Associazione e il personale di segreteria augurano a tutti Buon Natale e Felice Anno Nuovo<\/span><\/em><\/strong><\/p>\n<p><a href=\"http:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2016\/12\/Palline-di-natale-rosse.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-10953\" src=\"http:\/\/www.geometrire.it\/associazione\/wp-content\/uploads\/sites\/7\/2016\/12\/Palline-di-natale-rosse.jpg\" alt=\"palline-di-natale-rosse\" width=\"230\" height=\"295\" \/><\/a><\/p>\n<p><span style=\"color: #ff0000;\">Gli Uffici di Segreteria del Collegio Geometri e Geometri Laureati e Associazione dei Geometri della Provincia di Reggio Emilia<\/span><br \/>\n<span style=\"color: #ff0000;\"> EFFETTUERANNO LA CHIUSURA PER FERIE<\/span><br \/>\n<span style=\"color: #ff0000;\"> dal 27 dicembre 2016 al 5 gennaio 2017 &#8211; riapertura luned\u00ec\u00a09 gennaio 2017<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Consigli Direttivi di Collegio e Associazione e il personale di segreteria augurano a tutti Buon Natale e Felice Anno Nuovo Gli Uffici di Segreteria del Collegio Geometri e Geometri Laureati e Associazione dei Geometri della Provincia di Reggio Emilia EFFETTUERANNO LA CHIUSURA PER FERIE dal 27 dicembre 2016 al 5 gennaio 2017 &#8211; riapertura luned\u00ec\u00a09 gennaio 2017<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/10936"}],"collection":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/comments?post=10936"}],"version-history":[{"count":7,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/10936\/revisions"}],"predecessor-version":[{"id":10954,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/posts\/10936\/revisions\/10954"}],"wp:attachment":[{"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/media?parent=10936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/categories?post=10936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geometrire.it\/associazione\/wp-json\/wp\/v2\/tags?post=10936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}